{"id":150,"date":"2020-03-14T14:14:40","date_gmt":"2020-03-14T14:14:40","guid":{"rendered":"http:\/\/127.0.0.1:10080\/wordpress\/?p=150"},"modified":"2020-03-14T14:14:40","modified_gmt":"2020-03-14T14:14:40","slug":"information-coronavirus","status":"publish","type":"post","link":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/14\/information-coronavirus\/","title":{"rendered":"Information Coronavirus"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Les messes de samedi \u00e0 18h30 \u00e0 Notre Dame des Ap\u00f4tres  et de dimanche \u00e0 11h \u00e0 St Andr\u00e9 sont maintenues mais avec une assembl\u00e9e limit\u00e9e \u00e0 100 personnes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Merci de bien vouloir respecter  les pr\u00e9cautions sanitaires n\u00e9cessaires : espacement entre les personnes, mains lav\u00e9es pour ceux qui donnent la communion, communion donn\u00e9e dans la main,  pas de poign\u00e9e de main &#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les messes de samedi \u00e0 18h30 \u00e0 Notre Dame des Ap\u00f4tres et de dimanche \u00e0 11h \u00e0 St Andr\u00e9 sont maintenues mais avec une assembl\u00e9e [&hellip;] <span class=\"read-more-link\"><a class=\"read-more\" href=\"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/14\/information-coronavirus\/\">Read More<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-150","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Information Coronavirus - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire<\/title>\n<meta name=\"description\" content=\"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/14\/information-coronavirus\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Information Coronavirus - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire\" \/>\n<meta property=\"og:description\" content=\"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/14\/information-coronavirus\/\" \/>\n<meta property=\"og:site_name\" content=\"Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-14T14:14:40+00:00\" \/>\n<meta name=\"author\" content=\"admin9493\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin9493\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/14\\\/information-coronavirus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/14\\\/information-coronavirus\\\/\"},\"author\":{\"name\":\"admin9493\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#\\\/schema\\\/person\\\/40d6261e73db3d0db9cdb67a5dd3b8c7\"},\"headline\":\"Information Coronavirus\",\"datePublished\":\"2020-03-14T14:14:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/14\\\/information-coronavirus\\\/\"},\"wordCount\":64,\"publisher\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#organization\"},\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/14\\\/information-coronavirus\\\/\",\"url\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/14\\\/information-coronavirus\\\/\",\"name\":\"Information Coronavirus - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#website\"},\"datePublished\":\"2020-03-14T14:14:40+00:00\",\"description\":\"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/14\\\/information-coronavirus\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/14\\\/information-coronavirus\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/14\\\/information-coronavirus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Information Coronavirus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#website\",\"url\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/\",\"name\":\"Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire\",\"description\":\"Saint-Pierre -  Saint-Paul - Saint-Andr\u00e9 -  Notre-Dame des Ap\u00f4tres - Notre-Dame du Rosaire \",\"publisher\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#organization\",\"name\":\"Paroisses de la Pentecote Saint-Paul Notre-Dame du Rosaire\",\"url\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/logo-commun.png\",\"contentUrl\":\"http:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/logo-commun.png\",\"width\":453,\"height\":235,\"caption\":\"Paroisses de la Pentecote Saint-Paul Notre-Dame du Rosaire\"},\"image\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#\\\/schema\\\/person\\\/40d6261e73db3d0db9cdb67a5dd3b8c7\",\"name\":\"admin9493\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g\",\"caption\":\"admin9493\"},\"url\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/author\\\/admin9493\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Information Coronavirus - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire","description":"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/14\/information-coronavirus\/","og_locale":"fr_FR","og_type":"article","og_title":"Information Coronavirus - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire","og_description":"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.","og_url":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/14\/information-coronavirus\/","og_site_name":"Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire","article_published_time":"2020-03-14T14:14:40+00:00","author":"admin9493","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin9493"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/14\/information-coronavirus\/#article","isPartOf":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/14\/information-coronavirus\/"},"author":{"name":"admin9493","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#\/schema\/person\/40d6261e73db3d0db9cdb67a5dd3b8c7"},"headline":"Information Coronavirus","datePublished":"2020-03-14T14:14:40+00:00","mainEntityOfPage":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/14\/information-coronavirus\/"},"wordCount":64,"publisher":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#organization"},"articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/14\/information-coronavirus\/","url":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/14\/information-coronavirus\/","name":"Information Coronavirus - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire","isPartOf":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#website"},"datePublished":"2020-03-14T14:14:40+00:00","description":"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.","breadcrumb":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/14\/information-coronavirus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/14\/information-coronavirus\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/14\/information-coronavirus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/paroissespentecotesaintpaul.ovh\/"},{"@type":"ListItem","position":2,"name":"Information Coronavirus"}]},{"@type":"WebSite","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#website","url":"https:\/\/paroissespentecotesaintpaul.ovh\/","name":"Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire","description":"Saint-Pierre -  Saint-Paul - Saint-Andr\u00e9 -  Notre-Dame des Ap\u00f4tres - Notre-Dame du Rosaire ","publisher":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paroissespentecotesaintpaul.ovh\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#organization","name":"Paroisses de la Pentecote Saint-Paul Notre-Dame du Rosaire","url":"https:\/\/paroissespentecotesaintpaul.ovh\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#\/schema\/logo\/image\/","url":"http:\/\/paroissespentecotesaintpaul.ovh\/wp-content\/uploads\/2020\/09\/logo-commun.png","contentUrl":"http:\/\/paroissespentecotesaintpaul.ovh\/wp-content\/uploads\/2020\/09\/logo-commun.png","width":453,"height":235,"caption":"Paroisses de la Pentecote Saint-Paul Notre-Dame du Rosaire"},"image":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#\/schema\/person\/40d6261e73db3d0db9cdb67a5dd3b8c7","name":"admin9493","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g","caption":"admin9493"},"url":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/author\/admin9493\/"}]}},"_links":{"self":[{"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/posts\/150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/comments?post=150"}],"version-history":[{"count":0,"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/posts\/150\/revisions"}],"wp:attachment":[{"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/media?parent=150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/categories?post=150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/tags?post=150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}