{"id":2188,"date":"2020-03-25T09:33:11","date_gmt":"2020-03-25T08:33:11","guid":{"rendered":"http:\/\/paroissedelapentecote.fr\/?p=2188"},"modified":"2020-03-25T09:33:11","modified_gmt":"2020-03-25T08:33:11","slug":"je-crie-vers-toi-seigneur-toi-mon-secours","status":"publish","type":"post","link":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/25\/je-crie-vers-toi-seigneur-toi-mon-secours\/","title":{"rendered":"Je crie vers Toi Seigneur, toi mon secours"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Je crie vers Toi Seigneur, toi mon secours<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seigneur, ces derniers jours sont un grand bouleversement dans nos habitudes, dans nos certitudes, dans nos conforts, dans nos besoins. <br>\nNous vivons peurs, frustrations, questionnements ; nous ne savons que dire et quoi penser.<br>\nNos esprits sont submerg\u00e9s d\u2019informations de toutes parts.<br>\nMais dans ce flou et cette angoisse, nous sommes interpel\u00e9s par des appels \u00e0 la pri\u00e8re dans nos confinements et dans nos foyers. <br>\nDes initiatives voient le jour et j\u2019ai l\u2019impression que les rayons de soleil tentent de traverser les nuages. Nous apercevons \u00e0 peine ces rayons mais nous en ressentons d\u2019ores et d\u00e9j\u00e0 la chaleur, le r\u00e9confort, la force qui traverse tout. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au soir de nos d\u00e9tresses, ne nous abandonne pas Seigneur. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Te priant, te criant ma peur Seigneur, j\u2019ai l\u2019impression que je manque de confiance et de foi. <br>\nMais mon amour pour toi est si grand que l\u2019\u00e9lan \u00e0 te prier l\u2019emporte. <br>\nComme un enfant appelle ses parents quand il a peur, vers toi, s\u2019\u00e9l\u00e8ve ma voix et se tourne mon c\u0153ur.  <br>\nLe Christ au jardin de Geths\u00e9mani implorait l\u2019\u00e9loignement de la coupe ; je te prie Seigneur de nous donner force et esp\u00e9rance pour vivre ces moments. \u00c9pargne-nous le fl\u00e9au de l\u2019\u00e9pid\u00e9mie. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je te prie :<br>\n\u2022    Pour tous ceux que j\u2019aime et qui vivent \u00e0 leur mani\u00e8re ces m\u00eames instants troublants, <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022    Pour les soignants,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022    Pour ceux qui continuent leur travail pour que nous puissions trouver la nourriture n\u00e9cessaire au quotidien de nos vies.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022    Pour que ces temps de pri\u00e8res n\u00e9s de ces temps troubl\u00e9s perdurent dans le temps car ils sont lumi\u00e8res sur notre chemin, un chemin qui m\u00e8ne \u00e0 Toi Dieu d\u2019amour. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022    Pour que nous sachions regarder avec tes yeux et voir l\u2019esp\u00e9rance, la fraternit\u00e9, l\u2019amour, chaque instant de nos vies. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022    Pour que nos mains soient les instruments de ton amour envers nos fr\u00e8res et s\u0153urs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022    Et enfin pour que nous gardions le go\u00fbt de l\u2019essentiel, mets en nous un esprit nouveau qui ose innover pour faire grandir l\u2019humanit\u00e9. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seigneur, \u00e9coute-nous, seigneur exauce-nous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caroline <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je crie vers Toi Seigneur, toi mon secours Seigneur, ces derniers jours sont un grand bouleversement dans nos habitudes, dans nos certitudes, dans nos conforts, [&hellip;] <span class=\"read-more-link\"><a class=\"read-more\" href=\"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/25\/je-crie-vers-toi-seigneur-toi-mon-secours\/\">Read More<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":597,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Je crie vers Toi Seigneur, toi mon secours - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire<\/title>\n<meta name=\"description\" content=\"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/25\/je-crie-vers-toi-seigneur-toi-mon-secours\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Je crie vers Toi Seigneur, toi mon secours - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire\" \/>\n<meta property=\"og:description\" content=\"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/25\/je-crie-vers-toi-seigneur-toi-mon-secours\/\" \/>\n<meta property=\"og:site_name\" content=\"Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-25T08:33:11+00:00\" \/>\n<meta name=\"author\" content=\"admin9493\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin9493\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/25\\\/je-crie-vers-toi-seigneur-toi-mon-secours\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/25\\\/je-crie-vers-toi-seigneur-toi-mon-secours\\\/\"},\"author\":{\"name\":\"admin9493\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#\\\/schema\\\/person\\\/40d6261e73db3d0db9cdb67a5dd3b8c7\"},\"headline\":\"Je crie vers Toi Seigneur, toi mon secours\",\"datePublished\":\"2020-03-25T08:33:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/25\\\/je-crie-vers-toi-seigneur-toi-mon-secours\\\/\"},\"wordCount\":379,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/25\\\/je-crie-vers-toi-seigneur-toi-mon-secours\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/25\\\/je-crie-vers-toi-seigneur-toi-mon-secours\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/25\\\/je-crie-vers-toi-seigneur-toi-mon-secours\\\/\",\"url\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/25\\\/je-crie-vers-toi-seigneur-toi-mon-secours\\\/\",\"name\":\"Je crie vers Toi Seigneur, toi mon secours - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/25\\\/je-crie-vers-toi-seigneur-toi-mon-secours\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/25\\\/je-crie-vers-toi-seigneur-toi-mon-secours\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2020-03-25T08:33:11+00:00\",\"description\":\"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/25\\\/je-crie-vers-toi-seigneur-toi-mon-secours\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/25\\\/je-crie-vers-toi-seigneur-toi-mon-secours\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/25\\\/je-crie-vers-toi-seigneur-toi-mon-secours\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/25\\\/je-crie-vers-toi-seigneur-toi-mon-secours\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Je crie vers Toi Seigneur, toi mon secours\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#website\",\"url\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/\",\"name\":\"Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire\",\"description\":\"Saint-Pierre -  Saint-Paul - Saint-Andr\u00e9 -  Notre-Dame des Ap\u00f4tres - Notre-Dame du Rosaire \",\"publisher\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#organization\",\"name\":\"Paroisses de la Pentecote Saint-Paul Notre-Dame du Rosaire\",\"url\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/logo-commun.png\",\"contentUrl\":\"http:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/logo-commun.png\",\"width\":453,\"height\":235,\"caption\":\"Paroisses de la Pentecote Saint-Paul Notre-Dame du Rosaire\"},\"image\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#\\\/schema\\\/person\\\/40d6261e73db3d0db9cdb67a5dd3b8c7\",\"name\":\"admin9493\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g\",\"caption\":\"admin9493\"},\"url\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/author\\\/admin9493\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Je crie vers Toi Seigneur, toi mon secours - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire","description":"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/25\/je-crie-vers-toi-seigneur-toi-mon-secours\/","og_locale":"fr_FR","og_type":"article","og_title":"Je crie vers Toi Seigneur, toi mon secours - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire","og_description":"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.","og_url":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/25\/je-crie-vers-toi-seigneur-toi-mon-secours\/","og_site_name":"Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire","article_published_time":"2020-03-25T08:33:11+00:00","author":"admin9493","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin9493","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/25\/je-crie-vers-toi-seigneur-toi-mon-secours\/#article","isPartOf":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/25\/je-crie-vers-toi-seigneur-toi-mon-secours\/"},"author":{"name":"admin9493","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#\/schema\/person\/40d6261e73db3d0db9cdb67a5dd3b8c7"},"headline":"Je crie vers Toi Seigneur, toi mon secours","datePublished":"2020-03-25T08:33:11+00:00","mainEntityOfPage":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/25\/je-crie-vers-toi-seigneur-toi-mon-secours\/"},"wordCount":379,"commentCount":0,"publisher":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#organization"},"image":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/25\/je-crie-vers-toi-seigneur-toi-mon-secours\/#primaryimage"},"thumbnailUrl":"","inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/25\/je-crie-vers-toi-seigneur-toi-mon-secours\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/25\/je-crie-vers-toi-seigneur-toi-mon-secours\/","url":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/25\/je-crie-vers-toi-seigneur-toi-mon-secours\/","name":"Je crie vers Toi Seigneur, toi mon secours - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire","isPartOf":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#website"},"primaryImageOfPage":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/25\/je-crie-vers-toi-seigneur-toi-mon-secours\/#primaryimage"},"image":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/25\/je-crie-vers-toi-seigneur-toi-mon-secours\/#primaryimage"},"thumbnailUrl":"","datePublished":"2020-03-25T08:33:11+00:00","description":"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.","breadcrumb":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/25\/je-crie-vers-toi-seigneur-toi-mon-secours\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/25\/je-crie-vers-toi-seigneur-toi-mon-secours\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/25\/je-crie-vers-toi-seigneur-toi-mon-secours\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/25\/je-crie-vers-toi-seigneur-toi-mon-secours\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/paroissespentecotesaintpaul.ovh\/"},{"@type":"ListItem","position":2,"name":"Je crie vers Toi Seigneur, toi mon secours"}]},{"@type":"WebSite","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#website","url":"https:\/\/paroissespentecotesaintpaul.ovh\/","name":"Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire","description":"Saint-Pierre -  Saint-Paul - Saint-Andr\u00e9 -  Notre-Dame des Ap\u00f4tres - Notre-Dame du Rosaire ","publisher":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paroissespentecotesaintpaul.ovh\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#organization","name":"Paroisses de la Pentecote Saint-Paul Notre-Dame du Rosaire","url":"https:\/\/paroissespentecotesaintpaul.ovh\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#\/schema\/logo\/image\/","url":"http:\/\/paroissespentecotesaintpaul.ovh\/wp-content\/uploads\/2020\/09\/logo-commun.png","contentUrl":"http:\/\/paroissespentecotesaintpaul.ovh\/wp-content\/uploads\/2020\/09\/logo-commun.png","width":453,"height":235,"caption":"Paroisses de la Pentecote Saint-Paul Notre-Dame du Rosaire"},"image":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#\/schema\/person\/40d6261e73db3d0db9cdb67a5dd3b8c7","name":"admin9493","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g","caption":"admin9493"},"url":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/author\/admin9493\/"}]}},"_links":{"self":[{"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/posts\/2188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/comments?post=2188"}],"version-history":[{"count":0,"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/posts\/2188\/revisions"}],"wp:attachment":[{"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/media?parent=2188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/categories?post=2188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/tags?post=2188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}