{"id":4165,"date":"2024-05-29T10:41:27","date_gmt":"2024-05-29T08:41:27","guid":{"rendered":"https:\/\/paroissespentecotesaintpaul.ovh\/?p=4165"},"modified":"2024-05-29T10:41:29","modified_gmt":"2024-05-29T08:41:29","slug":"trait-dunion-n51","status":"publish","type":"post","link":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2024\/05\/29\/trait-dunion-n51\/","title":{"rendered":"Trait d&rsquo;Union n\u00b051"},"content":{"rendered":"\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/paroissespentecotesaintpaul.ovh\/wp-content\/uploads\/2024\/05\/TU-n\u00b051.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Contenu embarqu\u00e9 TU-n\u00b051.\"><\/object><a id=\"wp-block-file--media-749ed166-67b4-4a56-9913-447764d9f507\" href=\"https:\/\/paroissespentecotesaintpaul.ovh\/wp-content\/uploads\/2024\/05\/TU-n\u00b051.pdf\">TU-n\u00b051<\/a><a href=\"https:\/\/paroissespentecotesaintpaul.ovh\/wp-content\/uploads\/2024\/05\/TU-n\u00b051.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-749ed166-67b4-4a56-9913-447764d9f507\">T\u00e9l\u00e9charger<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-4165","post","type-post","status-publish","format-standard","hentry","category-trait-dunion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trait d&#039;Union n\u00b051 - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire<\/title>\n<meta name=\"description\" content=\"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2024\/05\/29\/trait-dunion-n51\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trait d&#039;Union n\u00b051 - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire\" \/>\n<meta property=\"og:description\" content=\"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2024\/05\/29\/trait-dunion-n51\/\" \/>\n<meta property=\"og:site_name\" content=\"Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-29T08:41:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-29T08:41:29+00:00\" \/>\n<meta name=\"author\" content=\"admin9493\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin9493\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2024\\\/05\\\/29\\\/trait-dunion-n51\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2024\\\/05\\\/29\\\/trait-dunion-n51\\\/\"},\"author\":{\"name\":\"admin9493\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#\\\/schema\\\/person\\\/40d6261e73db3d0db9cdb67a5dd3b8c7\"},\"headline\":\"Trait d&rsquo;Union n\u00b051\",\"datePublished\":\"2024-05-29T08:41:27+00:00\",\"dateModified\":\"2024-05-29T08:41:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2024\\\/05\\\/29\\\/trait-dunion-n51\\\/\"},\"wordCount\":8,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#organization\"},\"articleSection\":[\"Trait d'union\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2024\\\/05\\\/29\\\/trait-dunion-n51\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2024\\\/05\\\/29\\\/trait-dunion-n51\\\/\",\"url\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2024\\\/05\\\/29\\\/trait-dunion-n51\\\/\",\"name\":\"Trait d'Union n\u00b051 - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#website\"},\"datePublished\":\"2024-05-29T08:41:27+00:00\",\"dateModified\":\"2024-05-29T08:41:29+00:00\",\"description\":\"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2024\\\/05\\\/29\\\/trait-dunion-n51\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2024\\\/05\\\/29\\\/trait-dunion-n51\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2024\\\/05\\\/29\\\/trait-dunion-n51\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trait d&rsquo;Union n\u00b051\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#website\",\"url\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/\",\"name\":\"Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire\",\"description\":\"Saint-Pierre -  Saint-Paul - Saint-Andr\u00e9 -  Notre-Dame des Ap\u00f4tres - Notre-Dame du Rosaire \",\"publisher\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#organization\",\"name\":\"Paroisses de la Pentecote Saint-Paul Notre-Dame du Rosaire\",\"url\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/logo-commun.png\",\"contentUrl\":\"http:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/logo-commun.png\",\"width\":453,\"height\":235,\"caption\":\"Paroisses de la Pentecote Saint-Paul Notre-Dame du Rosaire\"},\"image\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#\\\/schema\\\/person\\\/40d6261e73db3d0db9cdb67a5dd3b8c7\",\"name\":\"admin9493\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g\",\"caption\":\"admin9493\"},\"url\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/author\\\/admin9493\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trait d'Union n\u00b051 - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire","description":"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2024\/05\/29\/trait-dunion-n51\/","og_locale":"fr_FR","og_type":"article","og_title":"Trait d'Union n\u00b051 - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire","og_description":"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.","og_url":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2024\/05\/29\/trait-dunion-n51\/","og_site_name":"Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire","article_published_time":"2024-05-29T08:41:27+00:00","article_modified_time":"2024-05-29T08:41:29+00:00","author":"admin9493","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin9493","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2024\/05\/29\/trait-dunion-n51\/#article","isPartOf":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2024\/05\/29\/trait-dunion-n51\/"},"author":{"name":"admin9493","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#\/schema\/person\/40d6261e73db3d0db9cdb67a5dd3b8c7"},"headline":"Trait d&rsquo;Union n\u00b051","datePublished":"2024-05-29T08:41:27+00:00","dateModified":"2024-05-29T08:41:29+00:00","mainEntityOfPage":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2024\/05\/29\/trait-dunion-n51\/"},"wordCount":8,"commentCount":0,"publisher":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#organization"},"articleSection":["Trait d'union"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2024\/05\/29\/trait-dunion-n51\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2024\/05\/29\/trait-dunion-n51\/","url":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2024\/05\/29\/trait-dunion-n51\/","name":"Trait d'Union n\u00b051 - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire","isPartOf":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#website"},"datePublished":"2024-05-29T08:41:27+00:00","dateModified":"2024-05-29T08:41:29+00:00","description":"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.","breadcrumb":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2024\/05\/29\/trait-dunion-n51\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2024\/05\/29\/trait-dunion-n51\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2024\/05\/29\/trait-dunion-n51\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/paroissespentecotesaintpaul.ovh\/"},{"@type":"ListItem","position":2,"name":"Trait d&rsquo;Union n\u00b051"}]},{"@type":"WebSite","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#website","url":"https:\/\/paroissespentecotesaintpaul.ovh\/","name":"Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire","description":"Saint-Pierre -  Saint-Paul - Saint-Andr\u00e9 -  Notre-Dame des Ap\u00f4tres - Notre-Dame du Rosaire ","publisher":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paroissespentecotesaintpaul.ovh\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#organization","name":"Paroisses de la Pentecote Saint-Paul Notre-Dame du Rosaire","url":"https:\/\/paroissespentecotesaintpaul.ovh\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#\/schema\/logo\/image\/","url":"http:\/\/paroissespentecotesaintpaul.ovh\/wp-content\/uploads\/2020\/09\/logo-commun.png","contentUrl":"http:\/\/paroissespentecotesaintpaul.ovh\/wp-content\/uploads\/2020\/09\/logo-commun.png","width":453,"height":235,"caption":"Paroisses de la Pentecote Saint-Paul Notre-Dame du Rosaire"},"image":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#\/schema\/person\/40d6261e73db3d0db9cdb67a5dd3b8c7","name":"admin9493","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g","caption":"admin9493"},"url":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/author\/admin9493\/"}]}},"_links":{"self":[{"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/posts\/4165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/comments?post=4165"}],"version-history":[{"count":1,"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/posts\/4165\/revisions"}],"predecessor-version":[{"id":4167,"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/posts\/4165\/revisions\/4167"}],"wp:attachment":[{"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/media?parent=4165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/categories?post=4165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/tags?post=4165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}