{"id":63,"date":"2020-03-06T18:00:40","date_gmt":"2020-03-06T18:00:40","guid":{"rendered":"http:\/\/127.0.0.1:10080\/wordpress\/?p=63"},"modified":"2020-03-06T18:00:40","modified_gmt":"2020-03-06T18:00:40","slug":"trait-dunion-n-7","status":"publish","type":"post","link":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/06\/trait-dunion-n-7\/","title":{"rendered":"TRAIT D&rsquo;UNION N\u00b0 7"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-64 size-full\" src=\"http:\/\/127.0.0.1:10080\/wordpress\/wp-content\/uploads\/2020\/03\/TU-7_1.png\" alt=\"\" width=\"515\" height=\"731\" \/><\/p>\n<p>Pour t\u00e9l\u00e9charger le Trait d&rsquo;Union n\u00b0 7 cliquez <a href=\"http:\/\/127.0.0.1:10080\/wordpress\/wp-content\/uploads\/2020\/03\/Tu-7.pdf\">ici<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour t\u00e9l\u00e9charger le Trait d&rsquo;Union n\u00b0 7 cliquez ici.<\/p>\n","protected":false},"author":1,"featured_media":68,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-63","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TRAIT D&#039;UNION N\u00b0 7 - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire<\/title>\n<meta name=\"description\" content=\"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/06\/trait-dunion-n-7\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TRAIT D&#039;UNION N\u00b0 7 - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire\" \/>\n<meta property=\"og:description\" content=\"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/06\/trait-dunion-n-7\/\" \/>\n<meta property=\"og:site_name\" content=\"Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-06T18:00:40+00:00\" \/>\n<meta name=\"author\" content=\"admin9493\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin9493\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/06\\\/trait-dunion-n-7\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/06\\\/trait-dunion-n-7\\\/\"},\"author\":{\"name\":\"admin9493\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#\\\/schema\\\/person\\\/40d6261e73db3d0db9cdb67a5dd3b8c7\"},\"headline\":\"TRAIT D&rsquo;UNION N\u00b0 7\",\"datePublished\":\"2020-03-06T18:00:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/06\\\/trait-dunion-n-7\\\/\"},\"wordCount\":15,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/06\\\/trait-dunion-n-7\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/06\\\/trait-dunion-n-7\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/06\\\/trait-dunion-n-7\\\/\",\"url\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/06\\\/trait-dunion-n-7\\\/\",\"name\":\"TRAIT D'UNION N\u00b0 7 - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/06\\\/trait-dunion-n-7\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/06\\\/trait-dunion-n-7\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2020-03-06T18:00:40+00:00\",\"description\":\"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/06\\\/trait-dunion-n-7\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/06\\\/trait-dunion-n-7\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/06\\\/trait-dunion-n-7\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/2020\\\/03\\\/06\\\/trait-dunion-n-7\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TRAIT D&rsquo;UNION N\u00b0 7\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#website\",\"url\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/\",\"name\":\"Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire\",\"description\":\"Saint-Pierre -  Saint-Paul - Saint-Andr\u00e9 -  Notre-Dame des Ap\u00f4tres - Notre-Dame du Rosaire \",\"publisher\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#organization\",\"name\":\"Paroisses de la Pentecote Saint-Paul Notre-Dame du Rosaire\",\"url\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/logo-commun.png\",\"contentUrl\":\"http:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/logo-commun.png\",\"width\":453,\"height\":235,\"caption\":\"Paroisses de la Pentecote Saint-Paul Notre-Dame du Rosaire\"},\"image\":{\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/#\\\/schema\\\/person\\\/40d6261e73db3d0db9cdb67a5dd3b8c7\",\"name\":\"admin9493\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g\",\"caption\":\"admin9493\"},\"url\":\"https:\\\/\\\/paroissespentecotesaintpaul.ovh\\\/index.php\\\/author\\\/admin9493\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TRAIT D'UNION N\u00b0 7 - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire","description":"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/06\/trait-dunion-n-7\/","og_locale":"fr_FR","og_type":"article","og_title":"TRAIT D'UNION N\u00b0 7 - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire","og_description":"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.","og_url":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/06\/trait-dunion-n-7\/","og_site_name":"Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire","article_published_time":"2020-03-06T18:00:40+00:00","author":"admin9493","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin9493"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/06\/trait-dunion-n-7\/#article","isPartOf":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/06\/trait-dunion-n-7\/"},"author":{"name":"admin9493","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#\/schema\/person\/40d6261e73db3d0db9cdb67a5dd3b8c7"},"headline":"TRAIT D&rsquo;UNION N\u00b0 7","datePublished":"2020-03-06T18:00:40+00:00","mainEntityOfPage":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/06\/trait-dunion-n-7\/"},"wordCount":15,"commentCount":0,"publisher":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#organization"},"image":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/06\/trait-dunion-n-7\/#primaryimage"},"thumbnailUrl":"","articleSection":["Uncategorized"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/06\/trait-dunion-n-7\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/06\/trait-dunion-n-7\/","url":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/06\/trait-dunion-n-7\/","name":"TRAIT D'UNION N\u00b0 7 - Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire","isPartOf":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#website"},"primaryImageOfPage":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/06\/trait-dunion-n-7\/#primaryimage"},"image":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/06\/trait-dunion-n-7\/#primaryimage"},"thumbnailUrl":"","datePublished":"2020-03-06T18:00:40+00:00","description":"Les Paroisses Saint-Paul Notre-Dame du Rosaire et La Pentec\u00f4te sont implant\u00e9es sur les communes de Rez\u00e9 et Bouguenais Les Cou\u00ebts.","breadcrumb":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/06\/trait-dunion-n-7\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/06\/trait-dunion-n-7\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/06\/trait-dunion-n-7\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/2020\/03\/06\/trait-dunion-n-7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/paroissespentecotesaintpaul.ovh\/"},{"@type":"ListItem","position":2,"name":"TRAIT D&rsquo;UNION N\u00b0 7"}]},{"@type":"WebSite","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#website","url":"https:\/\/paroissespentecotesaintpaul.ovh\/","name":"Paroisses de la Pentec\u00f4te et de Saint-Paul Notre-Dame du Rosaire","description":"Saint-Pierre -  Saint-Paul - Saint-Andr\u00e9 -  Notre-Dame des Ap\u00f4tres - Notre-Dame du Rosaire ","publisher":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paroissespentecotesaintpaul.ovh\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#organization","name":"Paroisses de la Pentecote Saint-Paul Notre-Dame du Rosaire","url":"https:\/\/paroissespentecotesaintpaul.ovh\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#\/schema\/logo\/image\/","url":"http:\/\/paroissespentecotesaintpaul.ovh\/wp-content\/uploads\/2020\/09\/logo-commun.png","contentUrl":"http:\/\/paroissespentecotesaintpaul.ovh\/wp-content\/uploads\/2020\/09\/logo-commun.png","width":453,"height":235,"caption":"Paroisses de la Pentecote Saint-Paul Notre-Dame du Rosaire"},"image":{"@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/paroissespentecotesaintpaul.ovh\/#\/schema\/person\/40d6261e73db3d0db9cdb67a5dd3b8c7","name":"admin9493","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff3e53271cc192222f32671178a20b120d0545bdd4dbce9152ab3e5e84c75697?s=96&d=mm&r=g","caption":"admin9493"},"url":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/author\/admin9493\/"}]}},"_links":{"self":[{"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/posts\/63","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/comments?post=63"}],"version-history":[{"count":0,"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/posts\/63\/revisions"}],"wp:attachment":[{"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/media?parent=63"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/categories?post=63"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paroissespentecotesaintpaul.ovh\/index.php\/wp-json\/wp\/v2\/tags?post=63"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}